{"id":7523,"date":"2016-10-08T13:15:08","date_gmt":"2016-10-08T17:15:08","guid":{"rendered":"https:\/\/jaxonphoto.com\/?p=7523"},"modified":"2019-08-10T21:45:11","modified_gmt":"2019-08-10T21:45:11","slug":"17th-st-bridge","status":"publish","type":"post","link":"https:\/\/www.jaxonphoto.com\/blog\/17th-st-bridge\/","title":{"rendered":"17th St Bridge &#038; Beltline Engagement"},"content":{"rendered":"<h2>17th St Bridge &amp; Atlanta Beltline Engagement Photo Session<\/h2>\n<p>Erica and Derrick&#8217;s engagement session, started at the Atlanta Beltline, North Avenue underpass next to Ponce City Market. Here the graffiti covered walls served up\u00a0a colorful backdrop for this leg of the couple&#8217;s photo session. The casually\u00a0dressed duo warmed up quickly to the camera, providing us with fun sexy\u00a0images to the delight of onlookers.\u00a0After a quick wardrobe change at our nearby Studioplex studio they were ready for part two. We ended the session on the 17th Street Bridge, gateway to Atlanta&#8217;s Atlantic Station.<\/p>\n<p>More\u00a0<a href=\"https:\/\/jaxonphoto.com\/category\/atlanta-beltline\/\">Beltline<\/a>\u00a0and\u00a0<a href=\"https:\/\/jaxonphoto.com\/category\/atlanta-engagement-pitures\/atlantic-station-engagement-photos\/\">17 Street Bridge<\/a>\u00a0photography sessions.<\/p>\n<p><a href=\"https:\/\/jaxonphoto.com\/17th-st-bridge\/sophistication-on-17th\/\" target=\"_blank\" rel=\"noopener noreferrer\"><img fetchpriority=\"high\" decoding=\"async\" class=\"alignleft wp-image-7531 size-full\" title=\"Sophistication on 17th\" src=\"https:\/\/jaxonphoto.com\/blog\/wp-content\/uploads\/2016\/08\/Atlanta-Beltline-Engagement-Photos-A35.jpg\" alt=\"Beautifully dressed young couple he is in a blue suite and she is wearing a metallic spaghetti strap plum dress, adding some sophistication on 17th St Bridge in Atlantic Station Atlanta\" width=\"980\" height=\"653\" srcset=\"https:\/\/www.jaxonphoto.com\/blog\/wp-content\/uploads\/2016\/08\/Atlanta-Beltline-Engagement-Photos-A35.jpg 980w, https:\/\/www.jaxonphoto.com\/blog\/wp-content\/uploads\/2016\/08\/Atlanta-Beltline-Engagement-Photos-A35-385x257.jpg 385w, https:\/\/www.jaxonphoto.com\/blog\/wp-content\/uploads\/2016\/08\/Atlanta-Beltline-Engagement-Photos-A35-768x512.jpg 768w\" sizes=\"(max-width: 980px) 100vw, 980px\" \/><\/a><\/p>\n<p><a href=\"https:\/\/jaxonphoto.com\/blog\/wp-content\/uploads\/2016\/08\/Atlanta-Beltline-Engagement-Photos-A34b.jpg\" target=\"_blank\" rel=\"noopener noreferrer\"><img decoding=\"async\" class=\"alignleft wp-image-7530 size-full\" title=\"Embrace 17th\" src=\"https:\/\/jaxonphoto.com\/blog\/wp-content\/uploads\/2016\/08\/Atlanta-Beltline-Engagement-Photos-A34b.jpg\" alt=\"Sepia toned image of couple embrace 17th street bridge gateway to Atlantic Station looking over I75\/85 to the midtown Atlanta skyline as a backdrop.\" width=\"980\" height=\"653\" srcset=\"https:\/\/www.jaxonphoto.com\/blog\/wp-content\/uploads\/2016\/08\/Atlanta-Beltline-Engagement-Photos-A34b.jpg 980w, https:\/\/www.jaxonphoto.com\/blog\/wp-content\/uploads\/2016\/08\/Atlanta-Beltline-Engagement-Photos-A34b-385x257.jpg 385w, https:\/\/www.jaxonphoto.com\/blog\/wp-content\/uploads\/2016\/08\/Atlanta-Beltline-Engagement-Photos-A34b-768x512.jpg 768w\" sizes=\"(max-width: 980px) 100vw, 980px\" \/><\/a><\/p>\n<p><a href=\"https:\/\/jaxonphoto.com\/blog\/wp-content\/uploads\/2016\/08\/Atlanta-Beltline-Engagement-Photos-A34.jpg\"><img decoding=\"async\" class=\"alignleft wp-image-7529 size-full\" src=\"https:\/\/jaxonphoto.com\/blog\/wp-content\/uploads\/2016\/08\/Atlanta-Beltline-Engagement-Photos-A34.jpg\" alt=\"Woman in evening dress against a brick wall during her engagement session\" width=\"693\" height=\"980\" srcset=\"https:\/\/www.jaxonphoto.com\/blog\/wp-content\/uploads\/2016\/08\/Atlanta-Beltline-Engagement-Photos-A34.jpg 693w, https:\/\/www.jaxonphoto.com\/blog\/wp-content\/uploads\/2016\/08\/Atlanta-Beltline-Engagement-Photos-A34-272x385.jpg 272w\" sizes=\"(max-width: 693px) 100vw, 693px\" \/><\/a><\/p>\n<p><a href=\"https:\/\/jaxonphoto.com\/blog\/wp-content\/uploads\/2016\/08\/Atlanta-Beltline-Engagement-Photos-A33.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-7528 size-full\" src=\"https:\/\/jaxonphoto.com\/blog\/wp-content\/uploads\/2016\/08\/Atlanta-Beltline-Engagement-Photos-A33.jpg\" alt=\"Sepia tone photograph of black male in suite posing agains brick wall\" width=\"653\" height=\"980\" srcset=\"https:\/\/www.jaxonphoto.com\/blog\/wp-content\/uploads\/2016\/08\/Atlanta-Beltline-Engagement-Photos-A33.jpg 653w, https:\/\/www.jaxonphoto.com\/blog\/wp-content\/uploads\/2016\/08\/Atlanta-Beltline-Engagement-Photos-A33-257x385.jpg 257w\" sizes=\"(max-width: 653px) 100vw, 653px\" \/><\/a><\/p>\n<p><a href=\"https:\/\/jaxonphoto.com\/blog\/wp-content\/uploads\/2016\/08\/Atlanta-Beltline-Engagement-Photos-A25.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-7532 size-full\" src=\"https:\/\/jaxonphoto.com\/blog\/wp-content\/uploads\/2016\/08\/Atlanta-Beltline-Engagement-Photos-A25.jpg\" alt=\"Atlanta Beltline underpass at North Ave\" width=\"960\" height=\"640\" srcset=\"https:\/\/www.jaxonphoto.com\/blog\/wp-content\/uploads\/2016\/08\/Atlanta-Beltline-Engagement-Photos-A25.jpg 960w, https:\/\/www.jaxonphoto.com\/blog\/wp-content\/uploads\/2016\/08\/Atlanta-Beltline-Engagement-Photos-A25-385x257.jpg 385w, https:\/\/www.jaxonphoto.com\/blog\/wp-content\/uploads\/2016\/08\/Atlanta-Beltline-Engagement-Photos-A25-768x512.jpg 768w\" sizes=\"(max-width: 960px) 100vw, 960px\" \/><\/a><\/p>\n<p><a href=\"https:\/\/jaxonphoto.com\/blog\/wp-content\/uploads\/2016\/08\/Atlanta-Beltline-Engagement-Photos-A27.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-7526 size-full\" src=\"https:\/\/jaxonphoto.com\/blog\/wp-content\/uploads\/2016\/08\/Atlanta-Beltline-Engagement-Photos-A27.jpg\" alt=\"Sepia portrait of engaged couple at Atlanta Beltline North Av underpass\" width=\"980\" height=\"653\" srcset=\"https:\/\/www.jaxonphoto.com\/blog\/wp-content\/uploads\/2016\/08\/Atlanta-Beltline-Engagement-Photos-A27.jpg 980w, https:\/\/www.jaxonphoto.com\/blog\/wp-content\/uploads\/2016\/08\/Atlanta-Beltline-Engagement-Photos-A27-385x257.jpg 385w, https:\/\/www.jaxonphoto.com\/blog\/wp-content\/uploads\/2016\/08\/Atlanta-Beltline-Engagement-Photos-A27-768x512.jpg 768w\" sizes=\"(max-width: 980px) 100vw, 980px\" \/><\/a><br \/>\n<a href=\"https:\/\/jaxonphoto.com\/blog\/wp-content\/uploads\/2016\/08\/Atlanta-Beltline-Engagement-Photos-A28.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-7527 size-full\" src=\"https:\/\/jaxonphoto.com\/blog\/wp-content\/uploads\/2016\/08\/Atlanta-Beltline-Engagement-Photos-A28.jpg\" alt=\"North Av underpass at the beltline in Atlanta \" width=\"980\" height=\"653\" srcset=\"https:\/\/www.jaxonphoto.com\/blog\/wp-content\/uploads\/2016\/08\/Atlanta-Beltline-Engagement-Photos-A28.jpg 980w, https:\/\/www.jaxonphoto.com\/blog\/wp-content\/uploads\/2016\/08\/Atlanta-Beltline-Engagement-Photos-A28-385x257.jpg 385w, https:\/\/www.jaxonphoto.com\/blog\/wp-content\/uploads\/2016\/08\/Atlanta-Beltline-Engagement-Photos-A28-768x512.jpg 768w\" sizes=\"(max-width: 980px) 100vw, 980px\" \/><\/a><\/p>\n<p><a href=\"https:\/\/jaxonphoto.com\/blog\/wp-content\/uploads\/2016\/08\/Atlanta-Beltline-Engagement-Photos-A26.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-7533 size-full\" src=\"https:\/\/jaxonphoto.com\/blog\/wp-content\/uploads\/2016\/08\/Atlanta-Beltline-Engagement-Photos-A26.jpg\" alt=\"Engagement Photography Session at the beltline Atlanta\" width=\"653\" height=\"980\" srcset=\"https:\/\/www.jaxonphoto.com\/blog\/wp-content\/uploads\/2016\/08\/Atlanta-Beltline-Engagement-Photos-A26.jpg 653w, https:\/\/www.jaxonphoto.com\/blog\/wp-content\/uploads\/2016\/08\/Atlanta-Beltline-Engagement-Photos-A26-257x385.jpg 257w\" sizes=\"(max-width: 653px) 100vw, 653px\" \/><\/a><\/p>\n<p><a href=\"https:\/\/jaxonphoto.com\/blog\/wp-content\/uploads\/2016\/10\/Atlanta-Beltline-Engagement-Photos-A22x.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-7545\" src=\"https:\/\/jaxonphoto.com\/blog\/wp-content\/uploads\/2016\/10\/Atlanta-Beltline-Engagement-Photos-A22x.jpg\" alt=\"Colorful graffiti walls at North Ave Beltline underpass\" width=\"662\" height=\"960\" srcset=\"https:\/\/www.jaxonphoto.com\/blog\/wp-content\/uploads\/2016\/10\/Atlanta-Beltline-Engagement-Photos-A22x.jpg 662w, https:\/\/www.jaxonphoto.com\/blog\/wp-content\/uploads\/2016\/10\/Atlanta-Beltline-Engagement-Photos-A22x-265x385.jpg 265w\" sizes=\"(max-width: 662px) 100vw, 662px\" \/><\/a><\/p>\n<p><a href=\"https:\/\/jaxonphoto.com\/blog\/wp-content\/uploads\/2016\/10\/Atlanta-Beltline-Engagement-Photos-A29.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-7544\" src=\"https:\/\/jaxonphoto.com\/blog\/wp-content\/uploads\/2016\/10\/Atlanta-Beltline-Engagement-Photos-A29.jpg\" alt=\"Atlanta Beltline Engagement Pics\" width=\"653\" height=\"980\" srcset=\"https:\/\/www.jaxonphoto.com\/blog\/wp-content\/uploads\/2016\/10\/Atlanta-Beltline-Engagement-Photos-A29.jpg 653w, https:\/\/www.jaxonphoto.com\/blog\/wp-content\/uploads\/2016\/10\/Atlanta-Beltline-Engagement-Photos-A29-257x385.jpg 257w\" sizes=\"(max-width: 653px) 100vw, 653px\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>17th St Bridge &amp; Atlanta Beltline Engagement Photo Session Erica and Derrick&#8217;s engagement session, started at the Atlanta Beltline, North Avenue underpass next to Ponce City Market. Here the graffiti covered walls served up\u00a0a colorful backdrop for this leg of the couple&#8217;s photo session. The casually\u00a0dressed duo warmed up quickly to the camera, providing us with fun sexy\u00a0images to the delight of onlookers.\u00a0After a quick wardrobe change at our nearby Studioplex studio they were ready for part two. We ended the session on the 17th Street Bridge, gateway to Atlanta&#8217;s Atlantic Station. More\u00a0Beltline\u00a0and\u00a017 Street Bridge\u00a0photography sessions.<\/p>\n","protected":false},"author":1,"featured_media":7531,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[138,24,4],"tags":[90,92,93,11,139,140,30,141],"class_list":["post-7523","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-17st-street-bridge","category-atlanta-beltline","category-atlanta-wedding-photography","tag-17-street-bridge","tag-atlantic-station-engagement-photos","tag-beltline","tag-engagement-photography-sessions","tag-graffiti","tag-north-av","tag-ponce-city-market","tag-studioplex"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v22.9 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>17th St Bridge &amp; Beltline Engagement | Atlanta Portrait and Event Photographers<\/title>\n<meta name=\"description\" content=\"17th St Bridge &amp; Beltline Engagement | \u00a0Erica and Derrick&#039;s engagement session started at the Beltline&#039;s North Av underpass next to Ponce City Market.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.jaxonphoto.com\/blog\/17th-st-bridge\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"17th St Bridge &amp; Beltline Engagement\" \/>\n<meta property=\"og:description\" content=\"17th St Bridge &amp; Beltline Engagement | \u00a0Erica and Derrick&#039;s engagement session started at the Beltline&#039;s North Av underpass next to Ponce City Market.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.jaxonphoto.com\/blog\/17th-st-bridge\/\" \/>\n<meta property=\"og:site_name\" content=\"Atlanta Portrait and Event Photographers\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/JaxonPhotography\/\" \/>\n<meta property=\"article:published_time\" content=\"2016-10-08T17:15:08+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-08-10T21:45:11+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.jaxonphoto.com\/blog\/wp-content\/uploads\/2016\/08\/Atlanta-Beltline-Engagement-Photos-A35.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"980\" \/>\n\t<meta property=\"og:image:height\" content=\"653\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"LR\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"LR\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.jaxonphoto.com\\\/blog\\\/17th-st-bridge\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.jaxonphoto.com\\\/blog\\\/17th-st-bridge\\\/\"},\"author\":{\"name\":\"LR\",\"@id\":\"https:\\\/\\\/www.jaxonphoto.com\\\/blog\\\/#\\\/schema\\\/person\\\/ea919cd8412381370c99f46fcd9a20fe\"},\"headline\":\"17th St Bridge &#038; Beltline Engagement\",\"datePublished\":\"2016-10-08T17:15:08+00:00\",\"dateModified\":\"2019-08-10T21:45:11+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.jaxonphoto.com\\\/blog\\\/17th-st-bridge\\\/\"},\"wordCount\":108,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.jaxonphoto.com\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.jaxonphoto.com\\\/blog\\\/17th-st-bridge\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.jaxonphoto.com\\\/blog\\\/wp-content\\\/uploads\\\/2016\\\/08\\\/Atlanta-Beltline-Engagement-Photos-A35.jpg\",\"keywords\":[\"17th St. Bridge\",\"Atlantic Station Engagement Sessions\",\"Beltline\",\"Engagement Photography Sessions\",\"graffiti\",\"North Av\",\"Ponce City Market\",\"Studioplex\"],\"articleSection\":[\"17st Street Bridge\",\"Atlanta Beltline\",\"Atlanta Wedding Photography\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.jaxonphoto.com\\\/blog\\\/17th-st-bridge\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.jaxonphoto.com\\\/blog\\\/17th-st-bridge\\\/\",\"url\":\"https:\\\/\\\/www.jaxonphoto.com\\\/blog\\\/17th-st-bridge\\\/\",\"name\":\"17th St Bridge & Beltline Engagement | Atlanta Portrait and Event Photographers\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.jaxonphoto.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.jaxonphoto.com\\\/blog\\\/17th-st-bridge\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.jaxonphoto.com\\\/blog\\\/17th-st-bridge\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.jaxonphoto.com\\\/blog\\\/wp-content\\\/uploads\\\/2016\\\/08\\\/Atlanta-Beltline-Engagement-Photos-A35.jpg\",\"datePublished\":\"2016-10-08T17:15:08+00:00\",\"dateModified\":\"2019-08-10T21:45:11+00:00\",\"description\":\"17th St Bridge & Beltline Engagement | \u00a0Erica and Derrick's engagement session started at the Beltline's North Av underpass next to Ponce City Market.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.jaxonphoto.com\\\/blog\\\/17th-st-bridge\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.jaxonphoto.com\\\/blog\\\/17th-st-bridge\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.jaxonphoto.com\\\/blog\\\/17th-st-bridge\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.jaxonphoto.com\\\/blog\\\/wp-content\\\/uploads\\\/2016\\\/08\\\/Atlanta-Beltline-Engagement-Photos-A35.jpg\",\"contentUrl\":\"https:\\\/\\\/www.jaxonphoto.com\\\/blog\\\/wp-content\\\/uploads\\\/2016\\\/08\\\/Atlanta-Beltline-Engagement-Photos-A35.jpg\",\"width\":980,\"height\":653,\"caption\":\"Beautifully dressed young couple he is in a blue suite and she is wearing a metallic spaghetti strap plum dress, adding some sophistication on 17th St Bridge in Atlantic Station Atlanta\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.jaxonphoto.com\\\/blog\\\/17th-st-bridge\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.jaxonphoto.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"17th St Bridge &#038; Beltline Engagement\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.jaxonphoto.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.jaxonphoto.com\\\/blog\\\/\",\"name\":\"Jaxon Photography | Event & Portrait Photography\",\"description\":\"Precision, Passion, and Timeless Moments \u2013 Your Photographers for Weddings, Portraits, Headshots, and Corporate Events.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.jaxonphoto.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.jaxonphoto.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.jaxonphoto.com\\\/blog\\\/#organization\",\"name\":\"Jaxon Photography\",\"alternateName\":\"Atlanta Event and Portrait Photographers\",\"url\":\"https:\\\/\\\/www.jaxonphoto.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.jaxonphoto.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/jaxon.goodgallery.com\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/08\\\/jaxon-logo.jpg\",\"contentUrl\":\"https:\\\/\\\/jaxon.goodgallery.com\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/08\\\/jaxon-logo.jpg\",\"width\":175,\"height\":175,\"caption\":\"Jaxon Photography\"},\"image\":{\"@id\":\"https:\\\/\\\/www.jaxonphoto.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/JaxonPhotography\\\/\",\"https:\\\/\\\/www.pinterest.com\\\/jaxonphoto\\\/\",\"https:\\\/\\\/instgram.com\\\/jaxonphoto\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.jaxonphoto.com\\\/blog\\\/#\\\/schema\\\/person\\\/ea919cd8412381370c99f46fcd9a20fe\",\"name\":\"LR\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2760635a9f9c4e989e2d5bf88c33af658115942f543bb38121e3ad4572028586?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2760635a9f9c4e989e2d5bf88c33af658115942f543bb38121e3ad4572028586?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2760635a9f9c4e989e2d5bf88c33af658115942f543bb38121e3ad4572028586?s=96&d=mm&r=g\",\"caption\":\"LR\"},\"sameAs\":[\"https:\\\/\\\/jaxonphoto.com\\\/\"],\"url\":\"https:\\\/\\\/www.jaxonphoto.com\\\/blog\\\/author\\\/jax0nph0t0\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"17th St Bridge & Beltline Engagement | Atlanta Portrait and Event Photographers","description":"17th St Bridge & Beltline Engagement | \u00a0Erica and Derrick's engagement session started at the Beltline's North Av underpass next to Ponce City Market.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.jaxonphoto.com\/blog\/17th-st-bridge\/","og_locale":"en_US","og_type":"article","og_title":"17th St Bridge & Beltline Engagement","og_description":"17th St Bridge & Beltline Engagement | \u00a0Erica and Derrick's engagement session started at the Beltline's North Av underpass next to Ponce City Market.","og_url":"https:\/\/www.jaxonphoto.com\/blog\/17th-st-bridge\/","og_site_name":"Atlanta Portrait and Event Photographers","article_publisher":"https:\/\/www.facebook.com\/JaxonPhotography\/","article_published_time":"2016-10-08T17:15:08+00:00","article_modified_time":"2019-08-10T21:45:11+00:00","og_image":[{"width":980,"height":653,"url":"https:\/\/www.jaxonphoto.com\/blog\/wp-content\/uploads\/2016\/08\/Atlanta-Beltline-Engagement-Photos-A35.jpg","type":"image\/jpeg"}],"author":"LR","twitter_card":"summary_large_image","twitter_misc":{"Written by":"LR","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.jaxonphoto.com\/blog\/17th-st-bridge\/#article","isPartOf":{"@id":"https:\/\/www.jaxonphoto.com\/blog\/17th-st-bridge\/"},"author":{"name":"LR","@id":"https:\/\/www.jaxonphoto.com\/blog\/#\/schema\/person\/ea919cd8412381370c99f46fcd9a20fe"},"headline":"17th St Bridge &#038; Beltline Engagement","datePublished":"2016-10-08T17:15:08+00:00","dateModified":"2019-08-10T21:45:11+00:00","mainEntityOfPage":{"@id":"https:\/\/www.jaxonphoto.com\/blog\/17th-st-bridge\/"},"wordCount":108,"commentCount":0,"publisher":{"@id":"https:\/\/www.jaxonphoto.com\/blog\/#organization"},"image":{"@id":"https:\/\/www.jaxonphoto.com\/blog\/17th-st-bridge\/#primaryimage"},"thumbnailUrl":"https:\/\/www.jaxonphoto.com\/blog\/wp-content\/uploads\/2016\/08\/Atlanta-Beltline-Engagement-Photos-A35.jpg","keywords":["17th St. Bridge","Atlantic Station Engagement Sessions","Beltline","Engagement Photography Sessions","graffiti","North Av","Ponce City Market","Studioplex"],"articleSection":["17st Street Bridge","Atlanta Beltline","Atlanta Wedding Photography"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.jaxonphoto.com\/blog\/17th-st-bridge\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.jaxonphoto.com\/blog\/17th-st-bridge\/","url":"https:\/\/www.jaxonphoto.com\/blog\/17th-st-bridge\/","name":"17th St Bridge & Beltline Engagement | Atlanta Portrait and Event Photographers","isPartOf":{"@id":"https:\/\/www.jaxonphoto.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.jaxonphoto.com\/blog\/17th-st-bridge\/#primaryimage"},"image":{"@id":"https:\/\/www.jaxonphoto.com\/blog\/17th-st-bridge\/#primaryimage"},"thumbnailUrl":"https:\/\/www.jaxonphoto.com\/blog\/wp-content\/uploads\/2016\/08\/Atlanta-Beltline-Engagement-Photos-A35.jpg","datePublished":"2016-10-08T17:15:08+00:00","dateModified":"2019-08-10T21:45:11+00:00","description":"17th St Bridge & Beltline Engagement | \u00a0Erica and Derrick's engagement session started at the Beltline's North Av underpass next to Ponce City Market.","breadcrumb":{"@id":"https:\/\/www.jaxonphoto.com\/blog\/17th-st-bridge\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.jaxonphoto.com\/blog\/17th-st-bridge\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.jaxonphoto.com\/blog\/17th-st-bridge\/#primaryimage","url":"https:\/\/www.jaxonphoto.com\/blog\/wp-content\/uploads\/2016\/08\/Atlanta-Beltline-Engagement-Photos-A35.jpg","contentUrl":"https:\/\/www.jaxonphoto.com\/blog\/wp-content\/uploads\/2016\/08\/Atlanta-Beltline-Engagement-Photos-A35.jpg","width":980,"height":653,"caption":"Beautifully dressed young couple he is in a blue suite and she is wearing a metallic spaghetti strap plum dress, adding some sophistication on 17th St Bridge in Atlantic Station Atlanta"},{"@type":"BreadcrumbList","@id":"https:\/\/www.jaxonphoto.com\/blog\/17th-st-bridge\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.jaxonphoto.com\/blog\/"},{"@type":"ListItem","position":2,"name":"17th St Bridge &#038; Beltline Engagement"}]},{"@type":"WebSite","@id":"https:\/\/www.jaxonphoto.com\/blog\/#website","url":"https:\/\/www.jaxonphoto.com\/blog\/","name":"Jaxon Photography | Event & Portrait Photography","description":"Precision, Passion, and Timeless Moments \u2013 Your Photographers for Weddings, Portraits, Headshots, and Corporate Events.","publisher":{"@id":"https:\/\/www.jaxonphoto.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.jaxonphoto.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.jaxonphoto.com\/blog\/#organization","name":"Jaxon Photography","alternateName":"Atlanta Event and Portrait Photographers","url":"https:\/\/www.jaxonphoto.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.jaxonphoto.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/jaxon.goodgallery.com\/blog\/wp-content\/uploads\/2019\/08\/jaxon-logo.jpg","contentUrl":"https:\/\/jaxon.goodgallery.com\/blog\/wp-content\/uploads\/2019\/08\/jaxon-logo.jpg","width":175,"height":175,"caption":"Jaxon Photography"},"image":{"@id":"https:\/\/www.jaxonphoto.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/JaxonPhotography\/","https:\/\/www.pinterest.com\/jaxonphoto\/","https:\/\/instgram.com\/jaxonphoto"]},{"@type":"Person","@id":"https:\/\/www.jaxonphoto.com\/blog\/#\/schema\/person\/ea919cd8412381370c99f46fcd9a20fe","name":"LR","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/2760635a9f9c4e989e2d5bf88c33af658115942f543bb38121e3ad4572028586?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2760635a9f9c4e989e2d5bf88c33af658115942f543bb38121e3ad4572028586?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2760635a9f9c4e989e2d5bf88c33af658115942f543bb38121e3ad4572028586?s=96&d=mm&r=g","caption":"LR"},"sameAs":["https:\/\/jaxonphoto.com\/"],"url":"https:\/\/www.jaxonphoto.com\/blog\/author\/jax0nph0t0\/"}]}},"acf":[],"_links":{"self":[{"href":"https:\/\/www.jaxonphoto.com\/blog\/wp-json\/wp\/v2\/posts\/7523","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jaxonphoto.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jaxonphoto.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jaxonphoto.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jaxonphoto.com\/blog\/wp-json\/wp\/v2\/comments?post=7523"}],"version-history":[{"count":1,"href":"https:\/\/www.jaxonphoto.com\/blog\/wp-json\/wp\/v2\/posts\/7523\/revisions"}],"predecessor-version":[{"id":134502,"href":"https:\/\/www.jaxonphoto.com\/blog\/wp-json\/wp\/v2\/posts\/7523\/revisions\/134502"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jaxonphoto.com\/blog\/wp-json\/wp\/v2\/media\/7531"}],"wp:attachment":[{"href":"https:\/\/www.jaxonphoto.com\/blog\/wp-json\/wp\/v2\/media?parent=7523"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jaxonphoto.com\/blog\/wp-json\/wp\/v2\/categories?post=7523"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jaxonphoto.com\/blog\/wp-json\/wp\/v2\/tags?post=7523"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}